{"id":5833,"date":"2026-03-16T14:04:44","date_gmt":"2026-03-16T14:04:44","guid":{"rendered":"https:\/\/dankew.me\/?page_id=5833"},"modified":"2026-03-16T14:06:41","modified_gmt":"2026-03-16T14:06:41","slug":"ravers-united","status":"publish","type":"page","link":"https:\/\/dankew.me\/index.php\/ravers-united\/","title":{"rendered":"Ravers United"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A short lived co-promotion with Elevation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1992<\/h2>\n\n\n\n<figure class=\"wp-block-table\">\n   <table class=\"has-fixed-layout\">\n      <thead>\n         <tr>\n            <th style=\"text-align:left\" width=\"25%\">Date<\/th>\n            <th style=\"text-align:left\" width=\"35%\">Venue<\/th>\n            <th style=\"text-align:left\" width=\"40%\">Event<\/th>\n         <\/tr>\n      <\/thead>\n      <tbody>\n         <tr>\n            <td>26th April &#8211; 17th May<\/td>\n            <td>Mona Lisa, Southall<\/td>\n            <td>&#8216;Ardcore!<\/td>\n         <\/tr>\n      <\/tbody>\n   <\/table>\n<\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a56f1a8c568b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a56f1a8c568b\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"721\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992-1024x721.png\" alt=\"\" class=\"wp-image-5829\" srcset=\"https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992-1024x721.png 1024w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992-300x211.png 300w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992-768x541.png 768w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992-1536x1081.png 1536w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992-2048x1442.png 2048w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992-624x439.png 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">April &amp; May 1992 &#8211; &#8216;Ardcore!<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a56f1a8c6f1e&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a56f1a8c6f1e\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"722\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992_2-1024x722.png\" alt=\"\" class=\"wp-image-5830\" srcset=\"https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992_2-1024x722.png 1024w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992_2-300x212.png 300w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992_2-768x542.png 768w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992_2-1536x1083.png 1536w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992_2-2048x1444.png 2048w, https:\/\/dankew.me\/wp-content\/uploads\/2026\/03\/ardcore-26-04-1992_2-624x440.png 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<\/div>\n\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><span class=\"wp-block-post-terms__prefix\"><strong>Tags<\/strong> &#8211; <\/span><a href=\"https:\/\/dankew.me\/index.php\/tag\/mona-lisa\/\" rel=\"tag\">Mona Lisa<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/dankew.me\/index.php\/tag\/ravers-united\/\" rel=\"tag\">Ravers United<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/dankew.me\/index.php\/tag\/southall\/\" rel=\"tag\">Southall<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>A short lived co-promotion with Elevation. 1992 Date Venue Event 26th April &#8211; 17th May Mona Lisa, Southall &#8216;Ardcore!<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[446],"tags":[1306,1305,1297],"class_list":["post-5833","page","type-page","status-publish","hentry","category-rave-organisers","tag-mona-lisa","tag-ravers-united","tag-southall"],"_links":{"self":[{"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/pages\/5833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/comments?post=5833"}],"version-history":[{"count":2,"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/pages\/5833\/revisions"}],"predecessor-version":[{"id":5836,"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/pages\/5833\/revisions\/5836"}],"wp:attachment":[{"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/media?parent=5833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/categories?post=5833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dankew.me\/index.php\/wp-json\/wp\/v2\/tags?post=5833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}